{"id":443419,"date":"2013-01-24T18:34:51","date_gmt":"2013-01-24T17:34:51","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=443419"},"modified":"2013-01-24T18:34:51","modified_gmt":"2013-01-24T17:34:51","slug":"443419","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/01\/24\/443419\/","title":{"rendered":"24\/1\/2013 &#8211; Conferenza Stampa di Presentazione della Coppa Europa"},"content":{"rendered":"<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/443419\/banner_european_cupart\/\" rel=\"attachment wp-att-443420\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-443420\" alt=\"Banner_european_cupart\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Banner_european_cupart.jpg\" width=\"450\" height=\"129\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Banner_european_cupart.jpg 450w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Banner_european_cupart-300x86.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Si e&#8217; svolta oggi a Dorga la Conferenza Stampa di presentazione della Coppa Europa \u00a0in programma il 2 e 3 febbraio 2013 al Monte Pora.<\/p>\n<p>Dell&#8217;evento vi proponiamo il video realizzato questa mattina presso le Residenze Acqua dei Pini.<\/p>\n<p>&nbsp;<\/p>\n<p>In allegato il comunicato\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Si e&#8217; svolta oggi a Dorga la Conferenza Stampa di presentazione della Coppa Europa \u00a0in programma il 2 e 3 febbraio 2013 al Monte Pora. Dell&#8217;evento vi proponiamo il video realizzato questa mattina presso le Residenze Acqua dei Pini. &nbsp; In allegato il comunicato\u00a0 &nbsp; &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":443421,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/443419"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=443419"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/443419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/443421"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=443419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=443419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=443419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}