{"id":440724,"date":"2013-01-22T12:22:27","date_gmt":"2013-01-22T11:22:27","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=440724"},"modified":"2013-01-22T12:22:27","modified_gmt":"2013-01-22T11:22:27","slug":"440724","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/01\/22\/440724\/","title":{"rendered":"22\/1\/2013 &#8211; Ski Race Cup seconda tappa: Foppolo 26-27 gennaio 2013"},"content":{"rendered":"<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div>\n<div><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/440724\/immagine2\/\" rel=\"attachment wp-att-440731\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-440731\" alt=\"Immagine[2]\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Immagine2.png\" width=\"342\" height=\"197\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Immagine2.png 342w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2013\/01\/Immagine2-300x173.png 300w\" sizes=\"(max-width: 342px) 100vw, 342px\" \/><\/a><\/div>\n<div>\u00a0<\/div>\n<\/div>\n<div>\u00a0<\/div>\n<div>\n<div>\u00a0<\/div>\n<p>Dopo il grande successo della prima tappa, il secondo appuntamento della Ski Race Cup \u00e8 fissato per i giorni<b>\u00a026 e\u00a0<a href=\"\/\/0\">27 gennaio<\/a>\u00a0a<\/b><b>\u00a0Foppolo,<\/b>nel cuore del comprensorio bergamasco Brembo Ski<b>.\u00a0<\/b>Si ripete anche quest\u2019anno la collaborazione con lo<b>\u00a0Sci Club Selvino<\/b>\u00a0che, insieme al nostro staff, sar\u00e0 alla regia delle quattro gare ad alto contenuto tecnico del weekend.\u00a0<b><a href=\"\/\/1\">Sabato 26 gennaio<\/a><\/b>\u00a0sulla pista Montebello si disputeranno uno<b>\u00a0slalom gigante\u00a0<\/b>e uno<b>\u00a0slalom speciale.\u00a0<\/b><b>D<\/b><b>omenica\u00a0<a href=\"\/\/2\">27 gennaio<\/a><\/b>\u00a0si bisser\u00e0 il programma della giornata precedente, con uno\u00a0<strong>slalom gigante<\/strong>\u00a0sempre seguito da uno\u00a0<b>slalom speciale<\/b>,validi in questo caso per la prima combinata di stagione, e con un\u2019altra importante differenza.<\/p>\n<div>\u00a0<\/div>\n<p>Lo slalom speciale di domenica infatti dar\u00e0 il via alla seconda edizione dell\u2019\u00a0<b>MKE Sport Team Cup<\/b>, una competizione a squadre il cui format \u00e8 gi\u00e0 stato sperimentato la scorsa stagione con un ottimo gradimento da parte degli atleti del Circuito, forse anche grazie al ricco montepremi di oltre \u20ac 3000. Vi invitiamo quindi a consultare il\u00a0<a href=\"https:\/\/www.skiracecup.it\/wordpress\/regolamento-mke-sport-team-cup-2013\" target=\"_blank\" rel=\"noopener\">Regolamento dell\u2019 MKE Sport Team Cup 2013<\/a>, rivisto e migliorato per garantire un maggiore equilibrio tra i valori delle squadre in pista, e a scaricare il\u00a0<a href=\"https:\/\/www.skiracecup.it\/wordpress\/storico\/2013\/MODULO%20di%20ISCRIZIONE%20TEAM%20CUP%202013.pdf\" target=\"_blank\" rel=\"noopener\">Modulo di Iscrizione<\/a>.<a href=\"https:\/\/www.skiracecup.it\/wordpress\/regolamento-mke-sport-team-cup-2013\"><br \/><\/a><\/p>\n<p>\u00a0In allegato\u00a0 trovate anche il programma ufficiale del weekend e il modulo di iscrizione all\u2019 Mke Sport Team Cup.<\/p>\n<p>\u00a0 Lo Staff Ski Race Cup vi aspetta al cancelletto di partenza, pronti a dare il via a questa nuova sfida.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/01\/Programma-gare-SCI-CLUB-SELVINO-Foppolo-26-27.01.-2013.pdf\" target=\"_blank\" rel=\"noopener\">Scarica il programma<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.fisialpicentrali.it\/cms\/wp-content\/uploads\/2013\/01\/MODULO-di-ISCRIZIONE-TEAM-CUP-2013.pdf\" target=\"_blank\" rel=\"noopener\"><\/p>\n<p>Scarica il modulo d&#8217;iscrizione<\/p>\n<p><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 Dopo il grande successo della prima tappa, il secondo appuntamento della Ski Race Cup \u00e8 fissato per i giorni\u00a026 e\u00a027 gennaio\u00a0a\u00a0Foppolo,nel cuore del comprensorio bergamasco Brembo Ski.\u00a0Si ripete anche quest\u2019anno la collaborazione con lo\u00a0Sci Club Selvino\u00a0che, insieme al nostro staff, sar\u00e0 alla regia delle quattro gare ad alto contenuto tecnico del weekend.\u00a0Sabato 26 gennaio\u00a0sulla pista Montebello si&hellip;<\/p>\n","protected":false},"author":4,"featured_media":428344,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/440724"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=440724"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/440724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/428344"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=440724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=440724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=440724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}