{"id":425963,"date":"2013-01-11T11:06:08","date_gmt":"2013-01-11T10:06:08","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=425963"},"modified":"2013-01-11T11:06:08","modified_gmt":"2013-01-11T10:06:08","slug":"1112013-comunicato","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/01\/11\/1112013-comunicato\/","title":{"rendered":"11\/1\/2013 &#8211; Comunicato"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Causa chiusura della stazione sciistica di Caspoggio, comunichiamo che le gare\u00a0<b>Indicative Pen.100 GS + SL<\/b>\u00a0\u2013\u00a0<b>CA048\/049<\/b>\u00a0previste in data\u00a0<b>29\/30.01.13<\/b>\u00a0organizzate dalla societ\u00e0 AS Caspoggio subiranno la seguente variazione:<\/p>\n<p>&nbsp;<\/p>\n<p><b>NUOVA LOCALITA\u2019<\/b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<b>BORMIO<\/b><\/p>\n<p><b>NUOVA ORGANIZZAZIONE<\/b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<b>S.C. BORMIO\u00a0<\/b>\u2013 Tel.+ Fax 0342.905009<\/p>\n<p><b>STESSE DATE<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Cordiali saluti.<\/p>\n<p>&nbsp;<\/p>\n<p>Alpi Centrali<\/p>\n<p>Franco Zecchini \u2013 Resp. Reg. Sci Alpino<\/p>\n<p>&nbsp;<\/p>\n<p>=================================<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Causa chiusura della stazione sciistica di Caspoggio, comunichiamo che le gare\u00a0Indicative Pen.100 GS + SL\u00a0\u2013\u00a0CA048\/049\u00a0previste in data\u00a029\/30.01.13\u00a0organizzate dalla societ\u00e0 AS Caspoggio subiranno la seguente variazione: &nbsp; NUOVA LOCALITA\u2019\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0BORMIO NUOVA ORGANIZZAZIONE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0S.C. BORMIO\u00a0\u2013 Tel.+ Fax 0342.905009 STESSE DATE &nbsp; Cordiali saluti. &nbsp; Alpi Centrali Franco Zecchini \u2013 Resp. Reg. Sci Alpino &nbsp; ================================= &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":405308,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/425963"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=425963"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/425963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/405308"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=425963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=425963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=425963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}