{"id":405304,"date":"2013-01-05T23:22:08","date_gmt":"2013-01-05T22:22:08","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=405304"},"modified":"2013-01-05T23:22:08","modified_gmt":"2013-01-05T22:22:08","slug":"512013-comunicato","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2013\/01\/05\/512013-comunicato\/","title":{"rendered":"5\/1\/2013 &#8211; Comunicato"},"content":{"rendered":"<p>Siamo spiacenti di comunicare che a causa di un \u00a0problema tecnico \u00a0le classifiche \u00a0non \u00a0vengono \u00a0pubblicate nei tempi auspicati. \u00a0I nostri tecnici assicurano che il problema verra&#8217; risolto al pi\u00f9 presto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo spiacenti di comunicare che a causa di un \u00a0problema tecnico \u00a0le classifiche \u00a0non \u00a0vengono \u00a0pubblicate nei tempi auspicati. \u00a0I nostri tecnici assicurano che il problema verra&#8217; risolto al pi\u00f9 presto.<\/p>\n","protected":false},"author":4,"featured_media":405308,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/405304"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=405304"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/405304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/405308"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=405304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=405304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=405304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}