{"id":396130,"date":"2012-12-15T22:47:42","date_gmt":"2012-12-15T21:47:42","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=396130"},"modified":"2012-12-15T22:47:42","modified_gmt":"2012-12-15T21:47:42","slug":"396130","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2012\/12\/15\/396130\/","title":{"rendered":"Sci Alpino Fis NJR di Madesimo"},"content":{"rendered":"<p>Alle Fis NJR a Madesimo ottimi risultati per gli atleti A C : ieri Matteo Baruffaldi vince lo slalom in campo maschile, e in campo femminile podio per Angelica Casartelli terza sempre nello slalom.<\/p>\n<p>Oggi era in programma ancora uno slalom maschile e ai primi due posti troviamo \u00a0Tommaso Sala \u00a0(nella foto) e Norman Cerini rispettivamente al primo e secondo posto.<\/p>\n<p><a href=\"https:\/\/www.fis-ski.com\/uk\/604\/610.html?sector=AL&amp;raceid=73871\" target=\"_blank\" rel=\"noopener\">classifica m 14-12<\/a><\/p>\n<p><a href=\"https:\/\/www.fis-ski.com\/uk\/604\/610.html?sector=AL&amp;raceid=73872\" target=\"_blank\" rel=\"noopener\">classifica f 14-12<\/a><\/p>\n<p><a href=\"https:\/\/www.fis-ski.com\/uk\/604\/610.html?sector=AL&amp;raceid=73873\" target=\"_blank\" rel=\"noopener\">classifica m 15-12<\/a><\/p>\n<p><a href=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fismadesimo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-396209\" title=\"fismadesimo\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fismadesimo.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fismadesimo.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fismadesimo-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fis2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-396210\" title=\"fis2\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fis2.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fis2.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fis2-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fis3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-396211\" title=\"fis3\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fis3.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fis3.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/12\/fis3-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle Fis NJR a Madesimo ottimi risultati per gli atleti A C : ieri Matteo Baruffaldi vince lo slalom in campo maschile, e in campo femminile podio per Angelica Casartelli terza sempre nello slalom. Oggi era in programma ancora uno slalom maschile e ai primi due posti troviamo \u00a0Tommaso Sala \u00a0(nella foto) e Norman Cerini rispettivamente al primo e secondo&hellip;<\/p>\n","protected":false},"author":4,"featured_media":396214,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/396130"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=396130"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/396130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/396214"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=396130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=396130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=396130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}