{"id":389485,"date":"2012-11-27T14:40:53","date_gmt":"2012-11-27T13:40:53","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=389485"},"modified":"2012-11-27T14:40:53","modified_gmt":"2012-11-27T13:40:53","slug":"27112012-coppa-europa-sci-alpino-azzola-ancora-sul-podio","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2012\/11\/27\/27112012-coppa-europa-sci-alpino-azzola-ancora-sul-podio\/","title":{"rendered":"27\/11\/2012 &#8211; Coppa Europa Sci Alpino: Azzola ancora sul podio"},"content":{"rendered":"<div>\n<div><\/div>\n<div>\n<div>\n<div><a href=\"https:\/\/www.fisi.org\/sites\/default\/files\/archivio\/michela%20azzola.jpg\" rel=\"lightbox[field_news_foto][&lt;a href=&quot;\/node\/49070&quot;&gt;&lt;\/a&gt;]\"><span style=\"color: #333333\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.fisi.org\/sites\/default\/files\/imagecache\/News_200px\/archivio\/michela%20azzola.jpg\" alt=\"&lt;a href=&quot;\/node\/49070&quot;&gt;&lt;\/a&gt;\" width=\"200\" height=\"138\" \/><\/span><\/a><\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<p>Dopo la brillante vittoria di luned\u00ec arriva un ottimo terzo posto per Michela Azzola nel secondo slalom di Coppa Europa a Vemdalen, in Svezia, era seconda nella prima manche. Per le altre italiane al 5\/o posto c&#8217;e&#8217; Sarah Pardeller, in grande recupero nella seconda frazione quando ha fatto registrare il secondo tempo assoluto. Bene anche Sofia Goggia 11\/a a seguire Nicole Agnelli 22\/a ma autrice del 10\/o tempo nella seconda manche ed entra in zona punti anche Michela Borgis 29\/a, anche lei in recupero nella seconda.<\/p>\n<p>Ordine d&#8217;arrivo slalom femminile CE di Vemdalen (Swe):<br \/>\n1. Magdalena Fjaellstroem Swe 1&#8217;19&#8243;98<br \/>\n2. Petra Vhlova Svk +0&#8243;21<br \/>\n<strong>3. Michela Azzola ITA +0&#8243;49<\/strong><br \/>\n3. Charlotta Saefvenberg Swe +0&#8243;49<br \/>\n<strong>5. Sarah Pardeller ITA +0&#8243;52<\/strong><br \/>\n6. Michelle Gisin Sui +0&#8243;68<br \/>\n7. Mona Loeseth NOR +1&#8243;15<br \/>\n8. Veronika Staber GER +1&#8243;22<br \/>\n9. Katharina Duerr GER +1&#8243;36<br \/>\n10. Adeline Baud FRA +1&#8243;38<br \/>\n<strong>11. Sofia Goggia ITA +1&#8243;45<\/strong><\/p>\n<p><strong>22. Nicole Agnelli ITA +2&#8243;35<br \/>\n29. Michela Borgis ITA +3&#8243;03<\/strong><\/p>\n<div><strong><br \/>\n<\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dopo la brillante vittoria di luned\u00ec arriva un ottimo terzo posto per Michela Azzola nel secondo slalom di Coppa Europa a Vemdalen, in Svezia, era seconda nella prima manche. Per le altre italiane al 5\/o posto c&#8217;e&#8217; Sarah Pardeller, in grande recupero nella seconda frazione quando ha fatto registrare il secondo tempo assoluto. Bene anche Sofia Goggia 11\/a a seguire&hellip;<\/p>\n","protected":false},"author":4,"featured_media":389531,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/389485"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=389485"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/389485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/389531"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=389485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=389485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=389485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}