{"id":389402,"date":"2012-11-26T19:19:31","date_gmt":"2012-11-26T18:19:31","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=389402"},"modified":"2012-11-26T19:19:31","modified_gmt":"2012-11-26T18:19:31","slug":"26112012-incontro-con-sci-club-nordico-e-alpino","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2012\/11\/26\/26112012-incontro-con-sci-club-nordico-e-alpino\/","title":{"rendered":"26\/11\/2012 &#8211; Incontro con Sci Club Nordico e Alpino"},"content":{"rendered":"<p><a href=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/11\/SKIPOOL1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-389410\" title=\"SKIPOOL\" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/11\/SKIPOOL1.jpg\" alt=\"\" width=\"600\" height=\"185\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/11\/SKIPOOL1.jpg 600w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2012\/11\/SKIPOOL1-300x93.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Lo<strong>\u00a0SKI\u00a0POOL BRIANZA<\/strong>\u00a0con la collaborazione di<strong>\u00a0SPORT SPECIALIST<\/strong>, organizza per<strong><span style=\"text-decoration: underline\">\u00a0venerdi\u00a030 novembre<\/span><\/strong>,<\/p>\n<p>un incontro con\u00a0<strong>Nicola Parolari<\/strong>, responsabile tecnico della ditta<strong>\u00a0SWIX<\/strong>.<\/p>\n<p>Nella serat\u00e0 che avr\u00e0<strong>\u00a0<span style=\"text-decoration: underline\">inizio alle 20,30<\/span><\/strong>\u00a0presso il<strong><span style=\"text-decoration: underline\">\u00a0negozio SPORT SPECIALIST di Lissone<\/span><\/strong>, saranno trattati gli elementi principali e l&#8217;imprtanza<\/p>\n<p>dello scorrimento e della tenuta nello sci.<\/p>\n<p><strong><span style=\"text-decoration: underline\">La serata \u00e8 aperta a tutti gli Sci Club di sci nordico e alpino.<\/span><\/strong><\/p>\n<p>Vi aspetiamo numerosi.<\/p>\n<p>Ski Pool Brianza<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo\u00a0SKI\u00a0POOL BRIANZA\u00a0con la collaborazione di\u00a0SPORT SPECIALIST, organizza per\u00a0venerdi\u00a030 novembre, un incontro con\u00a0Nicola Parolari, responsabile tecnico della ditta\u00a0SWIX. Nella serat\u00e0 che avr\u00e0\u00a0inizio alle 20,30\u00a0presso il\u00a0negozio SPORT SPECIALIST di Lissone, saranno trattati gli elementi principali e l&#8217;imprtanza dello scorrimento e della tenuta nello sci. La serata \u00e8 aperta a tutti gli Sci Club di sci nordico e alpino. Vi aspetiamo numerosi. Ski&hellip;<\/p>\n","protected":false},"author":4,"featured_media":389416,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25,9,10],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/389402"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=389402"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/389402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/389416"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=389402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=389402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=389402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}