{"id":389351,"date":"2012-11-23T21:15:07","date_gmt":"2012-11-23T20:15:07","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=389351"},"modified":"2012-11-23T21:15:07","modified_gmt":"2012-11-23T20:15:07","slug":"23112012-a-bergamo-un-corso-per-i-giudici-di-gara-dello-sci-alpino","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2012\/11\/23\/23112012-a-bergamo-un-corso-per-i-giudici-di-gara-dello-sci-alpino\/","title":{"rendered":"23\/11\/2012 &#8211;  A Bergamo un corso per i giudici di gara dello Sci Alpino"},"content":{"rendered":"<p>Si svolger\u00e0\u00a0domenica 25 novembre a Bergamo, presso la sede del CAI, un corso di aggiornamento rivolto ai giudici di gara dello sci alpino a livello nazionale. L\u2019evento \u00e8 stato promosso dal Presidente della Commissione Giudici\u00a0Marco Mapelli.<\/p>\n<p>La giornata di studio e di formazione sar\u00e0 incentrata prevalentemente sulle novit\u00e0 contenute nell\u2019Agenda dello Sciatore 2012 \u2013 2013 ed ancora tutte le novit\u00e0 in merito alla RTF 2012-2013. Nel corso della giornata saranno previsti anche test e lo studio di casi pratici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si svolger\u00e0\u00a0domenica 25 novembre a Bergamo, presso la sede del CAI, un corso di aggiornamento rivolto ai giudici di gara dello sci alpino a livello nazionale. L\u2019evento \u00e8 stato promosso dal Presidente della Commissione Giudici\u00a0Marco Mapelli. La giornata di studio e di formazione sar\u00e0 incentrata prevalentemente sulle novit\u00e0 contenute nell\u2019Agenda dello Sciatore 2012 \u2013 2013 ed ancora tutte le novit\u00e0&hellip;<\/p>\n","protected":false},"author":4,"featured_media":389352,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,10],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/389351"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=389351"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/389351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/389352"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=389351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=389351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=389351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}